{"id":1567,"date":"2026-05-13T00:05:32","date_gmt":"2026-05-12T22:05:32","guid":{"rendered":"https:\/\/entrepreneurmagazinerdc.com\/?p=1567"},"modified":"2026-05-13T00:05:34","modified_gmt":"2026-05-12T22:05:34","slug":"ecobank-et-le-bii-parient-sur-les-pme-pour-accelerer-la-transformation-economique","status":"publish","type":"post","link":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/2026\/05\/13\/ecobank-et-le-bii-parient-sur-les-pme-pour-accelerer-la-transformation-economique\/","title":{"rendered":"Ecobank et le BII parient sur les PME pour acc\u00e9l\u00e9rer la transformation \u00e9conomique"},"content":{"rendered":"\n<p>Dans une \u00e9conomie congolaise encore largement domin\u00e9e par les grandes industries extractives, les petites et moyennes entreprises peinent souvent \u00e0 acc\u00e9der aux financements capables de soutenir leur croissance. C\u2019est dans ce contexte que Ecobank RDC et British International Investment ont sign\u00e9, mardi 12 mai \u00e0 Kinshasa, un partenariat strat\u00e9gique de 30 millions de dollars destin\u00e9 au financement des PME congolaises.<\/p>\n\n\n\n<p>Le m\u00e9canisme repose sur une facilit\u00e9 de partage de risques permettant \u00e0 la banque panafricaine d\u2019\u00e9largir son portefeuille de cr\u00e9dits tout en limitant son exposition sur un march\u00e9 encore consid\u00e9r\u00e9 comme complexe par plusieurs investisseurs internationaux.<\/p>\n\n\n\n<p>Au-del\u00e0 du montant annonc\u00e9, l\u2019op\u00e9ration traduit surtout un changement progressif de perception autour du potentiel entrepreneurial congolais. Agriculture, agro-transformation, infrastructures, industrie l\u00e9g\u00e8re, climat et \u00e9nergies renouvelables figurent parmi les secteurs cibl\u00e9s \u2014 autant de segments identifi\u00e9s comme essentiels pour diversifier une \u00e9conomie encore d\u00e9pendante des mati\u00e8res premi\u00e8res.<\/p>\n\n\n\n<p>\u00ab Ce partenariat strat\u00e9gique avec British International Investment constitue une \u00e9tape majeure dans le renforcement de notre dispositif de financement des PME \u00bb, a d\u00e9clar\u00e9 Jo\u00ebl Kabuya, directeur g\u00e9n\u00e9ral ad int\u00e9rim d\u2019Ecobank RDC.<\/p>\n\n\n\n<p>Le BII, bras britannique du financement du d\u00e9veloppement, investit dans les march\u00e9s \u00e9mergents afin de soutenir la croissance et l\u2019emploi. Pour Viviane Infante, repr\u00e9sentante pays du BII, les PME congolaises demeurent confront\u00e9es \u00e0 \u00ab des obstacles majeurs pour acc\u00e9der au financement indispensable \u00e0 leur croissance \u00bb.<\/p>\n\n\n\n<p>Dieudonn\u00e9 Lukoji<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans une \u00e9conomie congolaise encore largement domin\u00e9e par les grandes industries extractives, les petites et moyennes entreprises peinent souvent \u00e0 acc\u00e9der aux financements capables de soutenir leur croissance. C\u2019est dans ce contexte que Ecobank RDC et British International Investment ont sign\u00e9, mardi 12 mai \u00e0 Kinshasa, un partenariat strat\u00e9gique de 30 millions de dollars destin\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[5,6],"tags":[397,80,121],"class_list":["post-1567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finances","category-news","tag-credit","tag-ecobank","tag-pme"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/posts\/1567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/comments?post=1567"}],"version-history":[{"count":1,"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/posts\/1567\/revisions"}],"predecessor-version":[{"id":1569,"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/posts\/1567\/revisions\/1569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/media\/1568"}],"wp:attachment":[{"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/media?parent=1567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/categories?post=1567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entrepreneurmagazinerdc.com\/index.php\/wp-json\/wp\/v2\/tags?post=1567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}